{"id":198349,"date":"2025-03-16T16:13:49","date_gmt":"2025-03-16T15:13:49","guid":{"rendered":"https:\/\/stayy.ch\/?post_type=travel-spot-guide&#038;p=198349"},"modified":"2025-03-16T16:13:49","modified_gmt":"2025-03-16T15:13:49","slug":"restaurant-uto-kulm","status":"publish","type":"travel-spot-guide","link":"https:\/\/stayy.ch\/es\/travel-spot-guide\/restaurant-uto-kulm\/","title":{"rendered":"Restaurante Uto Kulm"},"excerpt":{"rendered":"<p>Restaurante con vistas impresionantes<\/p>","protected":false},"template":"","travel-guide-category":[498,392],"class_list":["post-198349","travel-spot-guide","type-travel-spot-guide","status-publish","hentry","travel-guide-category-all-categories","travel-guide-category-places-to-eat"],"acf":[],"_links":{"self":[{"href":"https:\/\/stayy.ch\/es\/wp-json\/wp\/v2\/travel-spot-guide\/198349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stayy.ch\/es\/wp-json\/wp\/v2\/travel-spot-guide"}],"about":[{"href":"https:\/\/stayy.ch\/es\/wp-json\/wp\/v2\/types\/travel-spot-guide"}],"wp:attachment":[{"href":"https:\/\/stayy.ch\/es\/wp-json\/wp\/v2\/media?parent=198349"}],"wp:term":[{"taxonomy":"travel-guide-category","embeddable":true,"href":"https:\/\/stayy.ch\/es\/wp-json\/wp\/v2\/travel-guide-category?post=198349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}